{"id":20718,"date":"2024-08-30T17:22:38","date_gmt":"2024-08-30T09:22:38","guid":{"rendered":"https:\/\/thei.hhe-service.com\/?page_id=20718"},"modified":"2026-05-12T11:50:44","modified_gmt":"2026-05-12T03:50:44","slug":"professional-diploma-meister-power-electrical-engineering","status":"publish","type":"page","link":"https:\/\/thei.edu.hk\/tc\/departments\/department-of-construction-environment-and-engineering\/professional-diploma-meister-power-electrical-engineering\/","title":{"rendered":"\u96fb\u529b\u5de5\u7a0b\u5927\u5e2b\u7d1a\u5c08\u696d\u6587\u6191"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"20718\" class=\"elementor elementor-20718\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0906478 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0906478\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-572fc4e\" data-id=\"572fc4e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-527c5a1 elementor--h-position-center elementor--v-position-middle elementor-widget elementor-widget-slides\" data-id=\"527c5a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;none&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-293c4a8 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"DCEE-PD-PEE\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-8eeac62 e-flex e-con-boxed e-con e-parent\" data-id=\"8eeac62\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8dbb34f e-con-full e-flex e-con e-child\" data-id=\"8dbb34f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6990d4d e-flex e-con-boxed e-con e-child\" data-id=\"6990d4d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7aa5c13 e-flex e-con-boxed e-con e-child\" data-id=\"7aa5c13\" data-element_type=\"container\" data-e-type=\"container\" id=\"Programmeinfo\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eb270bf elementor-widget__width-initial elementor-widget thim-ekits-heading elementor-widget-thim-heading\" data-id=\"eb270bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"sc_heading\"><p class=\"title\">\u5b78\u7cfb : <\/p><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4296481 elementor-widget__width-initial elementor-widget thim-ekits-heading elementor-widget-thim-heading\" data-id=\"4296481\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"sc_heading\"><span class=\"title\">\u5efa\u9020\u3001\u74b0\u5883\u53ca\u5de5\u7a0b\u5b78\u7cfb <\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c437b04 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c437b04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b3bad9 elementor-widget__width-initial elementor-widget thim-ekits-heading elementor-widget-thim-heading\" data-id=\"4b3bad9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"sc_heading\"><p class=\"title\">\u8ab2\u7a0b\u540d\u7a31\ufe55 <\/p><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4470a9 elementor-widget__width-initial elementor-widget thim-ekits-heading elementor-widget-thim-heading\" data-id=\"c4470a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"sc_heading\"><span class=\"title\">\u96fb\u529b\u5de5\u7a0b\u5927\u5e2b\u7d1a\u5c08\u696d\u6587\u6191 <\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0151e71 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0151e71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-acbc24d elementor-widget__width-initial elementor-widget thim-ekits-heading elementor-widget-thim-heading\" data-id=\"acbc24d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"sc_heading\"><p class=\"title\">\u8ab2\u7a0b\u7de8\u865f : <\/p><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12ff397 elementor-widget__width-initial elementor-widget thim-ekits-heading elementor-widget-thim-heading\" data-id=\"12ff397\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"sc_heading\"><span class=\"title\">ST525108  <\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7566756 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7566756\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-100c0af elementor-widget__width-initial elementor-widget thim-ekits-heading elementor-widget-thim-heading\" data-id=\"100c0af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"sc_heading\"><p class=\"title\">\u5e74\u671f\ufe55 <\/p><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d426250 elementor-widget__width-initial elementor-widget thim-ekits-heading elementor-widget-thim-heading\" data-id=\"d426250\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"sc_heading\"><span class=\"title\">2\u5e74\uff08\u517c\u8b80\u5236-\u591c\u9593\uff09 <\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e496fab elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e496fab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e390de elementor-widget__width-initial elementor-widget thim-ekits-heading elementor-widget-thim-heading\" data-id=\"1e390de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"sc_heading\"><p class=\"title\">\u6559\u5b78\u8a9e\u8a00\ufe55 <\/p><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-642a9e4 elementor-widget__width-initial elementor-widget thim-ekits-heading elementor-widget-thim-heading\" data-id=\"642a9e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"sc_heading\"><span class=\"title\">\u82f1\u6587\u8f14\u4ee5\u4e2d\u6587 <\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0077ce elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d0077ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb9b062 elementor-widget__width-initial elementor-widget thim-ekits-heading elementor-widget-thim-heading\" data-id=\"cb9b062\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"sc_heading\"><p class=\"title\">\u4e0a\u8ab2\u5730\u9ede\ufe55 <\/p><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a49da90 elementor-widget__width-initial elementor-widget thim-ekits-heading elementor-widget-thim-heading\" data-id=\"a49da90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"sc_heading\"><span class=\"title\">\u9752\u8863\u6821\u5712 <br> \u5176\u4ed6\u6559\u5b78\u5730\u9ede:<\/p> <ul>   <li>\u8077\u696d\u8a13\u7df4\u5c40\u7d42\u8eab\u5b78\u7fd2\u4e2d\u5fc3<br>     \u9999\u6e2f\u4e5d\u9f8d\u9577\u6c99\u7063\u9577\u88d5\u885710\u865f\u5104\u4eac\u5ee3\u58342\u671f12\u6a13 D\u5ba4\u53caE\u5ba4<\/li>   <li>\u9999\u6e2f\u5c08\u696d\u6559\u80b2\u5b78\u9662(\u9752\u8863) \u65b0\u754c\u9752\u8863\u5cf6\u9752\u8863\u8def20\u865f<\/li>   <li class=\"translation-block\">\u9999\u6e2f\u5c08\u696d\u6559\u80b2\u5b78\u9662(\u9ec3\u514b\u7af6) ,<br>\n\u6d77\u508d\u6821\u820d(\u4e2d\u83ef\u96fb\u529b\u5de5\u7a0b\u5be6\u9a57\u5ba4), <br>\n\u4e5d\u9f8d\u9577\u6c99\u7063\u8354\u679d\u89d2\u9053879\u865f<\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-745c17a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"745c17a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2555d27 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2555d27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a6be08b e-con-full e-grid e-con e-child\" data-id=\"a6be08b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-863a27a elementor-widget elementor-widget-image\" data-id=\"863a27a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"157\" height=\"73\" src=\"https:\/\/thei.edu.hk\/wp-content\/uploads\/2024\/08\/QF_logo-SVG.svg\" class=\"attachment-full size-full wp-image-17979\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63a40dd elementor-widget elementor-widget-text-editor\" data-id=\"63a40dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u8ab2\u7a0b\u7372\u8cc7\u6b77\u67b6\u69cb\u8a8d\u53ef\u8cc7\u6b77\u67b6\u69cb\u7d1a\u5225: 5<br \/>\u8cc7\u6b77\u540d\u518a\u767b\u8a18\u865f\u78bc.: 23\/000364\/L5<br \/>\u8cc7\u6b77\u540d\u518a\u767b\u8a18\u6709\u6548\u671f: 01\/06\/2023 to 31\/08\/2026<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3058b6d elementor-widget thim-ekits-heading elementor-widget-thim-heading\" data-id=\"3058b6d\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"ProgrammeAims\" data-widget_type=\"thim-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"sc_heading\"><h2 class=\"title\">\u8ab2\u7a0b\u5b97\u65e8 <\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ba192e elementor-widget thim-ekits-heading elementor-widget-thim-heading\" data-id=\"7ba192e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"sc_heading\"><div class=\"sub-heading\"><p>\u5728\u96fb\u529b\u884c\u696d\u5408\u4f5c\u5925\u4f34\u548c\u5404\u6301\u5206\u8005\u7684\u5927\u529b\u652f\u6301\u4e0b\uff0c\u672c\u8ab2\u7a0b\u5df2\u7d93\u6210\u529f\u7372\u5f97\u9999\u6e2f\u5b78\u8853\u53ca\u8077\u696d\u8cc7\u6b77\u8a55\u5be9\u5c40 (HKCAAVQ) \u7684\u8a8d\u53ef\uff0c\u5c6c\u8cc7\u6b77\u67b6\u69cb\u7b2c\u4e94\u7d1a\u5225\uff0c\u4e26\u70ba\u9999\u6e2f\u8077\u696d\u5c08\u624d\u6559\u80b2 (VPET) \u767c\u5c55\u53d6\u5f97\u4e86\u91cd\u8981\u7a81\u7834\u3002\u672c\u8ab2\u7a0b\u4f5c\u70ba\u9999\u6e2f\u7b2c\u4e8c\u500b\u4ee5\u6280\u8853\u70ba\u672c\u7684\u5927\u5e2b\u7d1a\u8ab2\u7a0b\uff0c\u65e8\u5728\u70ba\u5177\u6709\u8c50\u5bcc\u96fb\u529b\u5de5\u7a0b\u5be6\u8e10\u7d93\u9a57\u7684\u5c08\u696d\u4eba\u58eb\u63d0\u4f9b\u5c08\u696d\u9032\u968e\u8def\u5f91\uff0c\u8b93\u4ed6\u5011\u80fd\u5920\u5b78\u7fd2\u4e26\u61c9\u7528\u96fb\u529b\u5de5\u7a0b\u5404\u500b\u5c08\u696d\u9818\u57df\u7684\u77e5\u8b58\u548c\u6280\u80fd\uff0c\u4ee5\u53ca\u638c\u63e1\u7ba1\u7406\u548c\u4eba\u624d\u57f9\u8a13\u7684\u6280\u5de7\uff0c\u6210\u70ba\u96fb\u529b\u5de5\u7a0b\u5927\u5e2b\uff08\u4ea6\u7a31\u6280\u80fd\u5927\u5e2b\/\u884c\u696d\u5927\u5e2b\uff09\u3002<\/p>\n<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f4c842 elementor-widget thim-ekits-heading elementor-widget-thim-heading\" data-id=\"5f4c842\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"Career\" data-widget_type=\"thim-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"sc_heading\"><h2 class=\"title\">\u5c31\u696d\u524d\u666f <\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c98fb9 elementor-widget thim-ekits-heading elementor-widget-thim-heading\" data-id=\"5c98fb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"sc_heading\"><div class=\"sub-heading\"><p>\u5b8c\u6210\u672c\u8ab2\u7a0b\u7684\u7562\u696d\u751f\u4e00\u822c\u53ef\u65bc\u96fb\u696d\u5de5\u7a0b\u516c\u53f8\u64d4\u4efb\u4e00\u4e9b\u6709\u95dc\u6280\u8853\u9805\u76ee\u548c\u71df\u904b\u7ba1\u7406\u7684\u9ad8\u7d1a\u8077\u4f4d\u3002\u96fb\u529b\u5de5\u7a0b\u5927\u5e2b\u4f5c\u70ba\u516c\u53f8\u7684\u6280\u8853\u9818\u5c0e\u5c64\uff0c\u5c07\u53ef\u5e36\u9818\u5718\u968a\u5354\u52a9\u9805\u76ee\u8ca0\u8cac\u4eba\u6216\u9805\u76ee\u8a2d\u8a08\u5de5\u7a0b\u5e2b\u3002<\/p>\n<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7a2eb3 elementor-widget thim-ekits-heading elementor-widget-thim-heading\" data-id=\"d7a2eb3\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"requirement\" data-widget_type=\"thim-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"sc_heading\"><h2 class=\"title\">\u5165\u5b78\u8981\u6c42 <\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66c6be1 elementor-widget elementor-widget-text-editor\" data-id=\"66c6be1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u6240\u6709\u7533\u8acb\u8005\u9808\u9032\u884c\u5165\u5b78\u7504\u9078\u53ca\u9762\u8a66\u3002\u672c\u8ab2\u7a0b\u7684\u6700\u4f4e\u5165\u5b78\u8981\u6c42\u5982\u4e0b\uff1a<\/p><ol><li>\u5c08\u696d\u548c\u7d93\u9a57\u8981\u6c42\uff1a<\/li><\/ol><ul><li>B\u7d1a\u96fb\u696d\u5de5\u7a0b\u4eba\u54e1(\u7b2c406\u7ae0) \u53ca\u5177\u6709\u81f3\u5c118\u5e74\u53d6\u5f97B\u7d1a\u96fb\u696d\u5de5\u7a0b\u4eba\u54e1\u8cc7\u683c\u5f8c\u7684\u5de5\u4f5c\u7d93\u9a57\u3002<\/li><\/ul><p><strong>\u53ca<\/strong><\/p><ol><li value=\"2\">\u5b78\u6b77\u548c\u7d93\u9a57\u8981\u6c42:<\/li><\/ol><ul><li>\u6301\u6709\u8cc7\u6b77\u67b6\u69cb\u7b2c4\u7d1a\u7684\u76f8\u95dc\u9ad8\u7d1a\u6587\u6191\u6216\u5c08\u696d\u6587\u6191\uff1b\u6216<\/li><li>\u6301\u6709\u88ab\u8ab2\u7a0b\u59d4\u54e1\u6703*\u8996\u70ba\u540c\u7b49\u5b78\u6b77\u3002\n*\u540c\u6642\u6301\u6709\u8cc7\u6b77\u67b6\u69cb\u4e0b\u7684\u300c\u904e\u5f80\u8cc7\u6b77\u8a8d\u53ef\u300d\u6a5f\u5236\u4e2d\u56db\u500b\u96fb\u6a5f\u5de5\u7a0b\u7b2c\u56db\u7d1a\u80fd\u529b\u55ae\u5143\u7d44\u5408\uff08\u5373\u4f4e\u58d3\u96fb\u529b\u88dd\u7f6e\u5b89\u88dd\u5de5\u4f5c\u3001\u4f4e\u58d3\u96fb\u529b\u88dd\u7f6e\u8a2d\u8a08\u5de5\u4f5c\u3001\u4f4e\u58d3\u96fb\u529b\u88dd\u7f6e\u4fdd\u990a\u7dad\u4fee\u5de5\u4f5c\u3001\u96fb\u529b\u88dd\u7f6e\u71df\u904b\u53ca\u7ba1\u7406\u5de5\u4f5c\uff09\u7684\u8a8d\u53ef\u904e\u5f80\u8cc7\u6b77\u5c07\u88ab\u8996\u70ba\u540c\u7b49\u6301\u6709\u88ab\u8ab2\u7a0b\u59d4\u54e1\u6703\u8a8d\u53ef\u7684\u5b78\u6b77\u3002\n\n\u7533\u8acb\u904e\u5f80\u8cc7\u6b77\u8a8d\u53ef\uff1ahttps:\/\/www.hkqf.gov.hk\/ems\/tc\/rpl\/application_procedures\/index.html<\/li><\/ul><p><em>*\u627f\u8a8d\u96fb\u6a5f\u5de5\u7a0b\u6240\u67094\u500b\u985e\u5225\u7684\u5148\u4fee\u5b78\u7fd2\uff08RPL\uff09\u8cc7\u683c\uff0c\u5747\u70baQF\u7b49\u7d1a4\uff0c\u5373\u4f4e\u58d3\u96fb\u529b\u5b89\u88dd\u3001\u4f4e\u58d3\u96fb\u529b\u4f9b\u61c9\u8a2d\u65bd\u8a2d\u8a08\u3001\u4f4e\u58d3\u96fb\u529b\u4f9b\u61c9\u8a2d\u65bd\u7dad\u4fee\u53ca\u4fdd\u990a\uff0c\u4ee5\u53ca\u96fb\u529b\u5b89\u88dd\u4f5c\u696d\u53ca\u7ba1\u7406\u88ab\u8996\u70ba\u9805\u76ee\u59d4\u54e1\u6703\u8a8d\u70ba\u540c\u7b49\u7684\u8cc7\u683c\u3002<\/em><\/p><p class=\"translation-block\"><em>RPL\u8cc7\u683c\u7533\u8acb\u9023\u7d50\uff1a<\/em><em><a href=\"https:\/\/www.hkqf.gov.hk\/ems\/en\/rpl\/application_procedures\/index.html\" data-auth=\"\u4e0d\u9069\u7528\" data-loopstyle=\"linkonly\" target=\"_self\">https:\/\/www.hkqf.gov.hk\/ems\/en\/rpl\/application_procedures\/index.html<\/a> \u00a0<\/em><\/p><p>\u5e74\u6eff35\u6b72\uff0c\u4e26\u4e14\u5177\u6709\u81f3\u5c1115\u5e74\u7684\u96fb\u529b\u5de5\u4f5c\u7d93\u9a57\uff0c\u5176\u4e2d\u4e0d\u5c11\u65bc5\u5e74\u7684B\u7d1a\u96fb\u696d\u5de5\u7a0b\u5de5\u4f5c\u7d93\u9a57\u7684\u7533\u8acb\u4eba\u4e5f\u53ef\u6309\u500b\u5225\u60c5\u6cc1\u8003\u616e\u53d6\u9304\u3002<\/p><p>\u7533\u8acb\u4eba\u5fc5\u9808\u901a\u904e\u5165\u5b78\u9762\u8a66\u4e26\u63d0\u4f9b\u96c7\u4e3b\u7684\u63d0\u540d\u4ee5\u4f9b\u5165\u5b78\u3002<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-266405e elementor-widget thim-ekits-heading elementor-widget-thim-heading\" data-id=\"266405e\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"Employer\" data-widget_type=\"thim-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"sc_heading\"><h2 class=\"title\">\u50f1\u4e3b\u63a8\u85a6\u53ca\u63d0\u540d <\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03180c3 elementor-widget elementor-widget-text-editor\" data-id=\"03180c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u7533\u8acb\u4eba\u9808\u7531\u50f1\u4e3b\u63d0\u540d\u4fee\u8b80\u8ab2\u7a0b\u3002\u50f1\u4e3b\u9808\u8072\u660e\u7533\u8acb\u4eba\u6240\u63d0\u4f9b\u6709\u95dc\u5de5\u4f5c\u7d93\u9a57\u7684\u8cc7\u6599\u5b8c\u6574\u4e26\u6b63\u78ba\u7121\u8aa4\uff0c\u4e26\u9808\u81f4\u529b\u70ba\u5b78\u751f\u63d0\u4f9b\u5145\u5206\u7684\u6a5f\u6703\u9032\u884c\u8077\u5834\u5b78\u7fd2\u53ca\u8a55\u6838(WLA)\uff0c\u5305\u62ec\uff1a<\/p><ul><li>\u70ba\u5b78\u751f\u5728\u5de5\u4f5c\u74b0\u5883\u4e2d\u63d0\u4f9b\u7372\u53d6\u77e5\u8b58\u548c\u6280\u80fd\u7684\u6a5f\u6703\uff1b<\/li><li>\u7c3d\u7f72\u5b78\u751f\u7684\u8077\u5834\u5b78\u7fd2\u53ca\u8a55\u6838\u65e5\u8a8c\uff1b<\/li><li>\u5206\u914d\u6709\u7d93\u9a57\u7684\u5de5\u4f5c\u4eba\u54e1\u64d4\u4efb\u57f9\u8a13\u5e2b\u3001\u6838\u67e5\u54e1\u548c\u8a55\u4f30\u54e1\uff1b\u53ca<\/li><li>\u65bc\u8077\u5834\u63d0\u4f9b\u6b63\u898f\u57f9\u8a13\uff0c\u4f8b\u5982\uff1a\u6d41\u7a0b\u6f14\u7df4\u3001\u5de5\u4f5c\u6642\u7684\u57f9\u8a13\u7b49\u3002<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0947e54 elementor-widget thim-ekits-heading elementor-widget-thim-heading\" data-id=\"0947e54\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"Recognition\" data-widget_type=\"thim-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"sc_heading\"><h2 class=\"title\">\uff23\u7d1a\u96fb\u696d\u5de5\u7a0b\u4eba\u54e1\u8a3b\u518a\u8003\u8a66\u8a8d\u53ef <\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b5b2354 elementor-widget elementor-widget-text-editor\" data-id=\"b5b2354\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u7562\u696d\u751f\u5982\u5728\u8ab2\u7a0b\u4e2d\u6307\u5b9a\u7684\u4e09\u500b\u55ae\u5143\uff0c\u5305\u62ec\u300c\u4f4e\u58d3\u96fb\u529b\u88dd\u7f6e\uff08\u4e00\uff09\u300d\u3001\u300c\u4f4e\u58d3\u96fb\u529b\u88dd\u7f6e\uff08\u4e8c\uff09\u300d\u53ca\u300c\u96fb\u529b\u7cfb\u7d71\u53ca\u96fb\u6a5f\u300d\u7684\u8003\u8a66\u5206\u5225\u65bc\u591a\u9805\u9078\u64c7\u984c\u53d6\u5f9770%\u5206\u6578\u53ca\u9577\u7b54\u984c\u53d6\u5f9750%\u5206\u6578\uff0c\u5c07\u88ab\u8996\u70ba\u65bc\u4e00\u9805\u7531\u6a5f\u96fb\u5de5\u7a0b\u7f72\u7f72\u9577\u8a8d\u53ef\u7684\uff23\u7d1a\u96fb\u696d\u5de5\u7a0b\u4eba\u54e1\u8a3b\u518a\u8003\u8a66\u4e2d\u53d6\u5f97\u5408\u683c\u3002<\/p><p>\u65bc\u4e0a\u8ff0\u76f8\u95dc\u7684\u55ae\u5143\u53d6\u5f97\u6307\u5b9a\u7684\u5408\u683c\u5206\u6578\u7684\u7562\u696d\u751f\u5728\u7533\u8acb\u8a3b\u518a\u6210\u70ba\uff23\u7d1a\u96fb\u696d\u5de5\u7a0b\u4eba\u54e1\u6642\uff0c\u4ecd\u9808\u7b26\u5408\u96fb\u529b\uff08\u8a3b\u518a\uff09\u898f\u4f8b\uff08\u7b2c406D\u7ae0\uff09\u7b2c6(2)(b)\u689d\u6240\u8a02\u660e\u7684\u5176\u4ed6\u76f8\u95dc\u898f\u5b9a\u3002<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14dcfab elementor-widget thim-ekits-heading elementor-widget-thim-heading\" data-id=\"14dcfab\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"fee\" data-widget_type=\"thim-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"sc_heading\"><h2 class=\"title\">\u5b78\u8cbb <\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-886a30f elementor-widget thim-ekits-heading elementor-widget-thim-heading\" data-id=\"886a30f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"sc_heading\"><div class=\"sub-heading\"><p>2025\/26\u5b78\u5e74\u7684\u8ab2\u7a0b\u7e3d\u5b78\u8cbb\u70ba\u6e2f\u5e6390,400\u3002<\/p>\n<p>(\u7576\u4e2d\u6e2f\u5e63$90,000\u70ba\u5b78\u8cbb\uff0c\u6e2f\u5e63$400\u70ba\u4fdd\u8b49\u91d1\u3002)<\/p>\n<p>\u5b78\u8cbb\u6c34\u5e73\u6bcf\u5e74\u6aa2\u8a0e\u3002<\/p>\n<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-feed78b elementor-widget thim-ekits-heading elementor-widget-thim-heading\" data-id=\"feed78b\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"curriculum\" data-widget_type=\"thim-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"sc_heading\"><h2 class=\"title\">\u8ab2\u7a0b\u7d50\u69cb <\/h2><div class=\"sub-heading\"><p id=\"ProgrammeCurricullum\">\n<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87c4a71 elementor-widget elementor-widget-text-editor\" data-id=\"87c4a71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<th><\/th>\n<th>\u55ae\u5143\u540d\u7a31<\/th>\n<th>\u8cc7\u6b77\u7d1a\u5225<\/th>\n<th>\u8cc7\u6b77\u5b78\u5206<\/th>\n<\/tr>\n<tr>\n<td rowspan=\"5\">\u4e00\u5e74\u7d1a<\/td>\n<td>\u4f4e\u58d3\u96fb\u529b\u88dd\u7f6e (\u4e00)<\/td>\n<td>5<\/td>\n<td>14.2<\/td>\n<\/tr>\n<tr>\n<td>\u884c\u696d\u7684\u6cd5\u5f8b\u548c\u7576\u4ee3\u554f\u984c<\/td>\n<td>4<\/td>\n<td>9.6<\/td>\n<\/tr>\n<tr>\n<td>\u4f4e\u58d3\u96fb\u529b\u88dd\u7f6e (\u4e8c)<\/td>\n<td>5<\/td>\n<td>14.2<\/td>\n<\/tr>\n<tr>\n<td>\u9805\u76ee\u53ca\u8cea\u5b89\u5065\u74b0\u7ba1\u7406<\/td>\n<td>5<\/td>\n<td>12.6<\/td>\n<\/tr>\n<tr>\n<td>\u96fb\u529b\u7cfb\u7d71\u53ca\u96fb\u6a5f<\/td>\n<td>5<\/td>\n<td>14.2<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"5\">\u4e8c\u5e74\u7d1a<\/td>\n<td>\u9ad8\u58d3\u96fb\u529b\u88dd\u7f6e<\/td>\n<td>5<\/td>\n<td>12.6<\/td>\n<\/tr>\n<tr>\n<td>\u5148\u9032\u79d1\u6280<\/td>\n<td>5<\/td>\n<td>12.6<\/td>\n<\/tr>\n<tr>\n<td>\u8cc7\u7522\u7ba1\u7406<\/td>\n<td>5<\/td>\n<td>12.6<\/td>\n<\/tr>\n<tr>\n<td>\u57f9\u8a13\u548c\u8f14\u5c0e<\/td>\n<td>5<\/td>\n<td>12.6<\/td>\n<\/tr>\n<tr>\n<td>\u884c\u696d\u5c08\u6848<\/td>\n<td>5<\/td>\n<td>14.8<\/td>\n<\/tr>\n<tr>\n<td>\u7e3d\u8a08<\/td>\n<td><\/td>\n<td><\/td>\n<td>130<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9374701 e-con-full e-flex e-con e-child\" data-id=\"9374701\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cb9f8e3 elementor-widget elementor-widget-thim-ekits-header-info\" data-id=\"cb9f8e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-ekits-header-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"header-info-swapper\">\n\t\t\t<ul class=\"thim-header-info\">\n\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#Programmeinfo\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\u8ab2\u7a0b\u8cc7\u8a0a\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#ProgrammeAims\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\u8ab2\u7a0b\u5b97\u65e8\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#Career\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\u5c31\u696d\u524d\u666f\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#Requirements\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\u5165\u5b78\u8981\u6c42\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#Employer\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\u50f1\u4e3b\u63a8\u85a6\u53ca\u63d0\u540d\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#Recognition\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\u5c08\u696d\u8a8d\u53ef\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#fee\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\u5b78\u8cbb\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#Curriculum\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\u8ab2\u7a0b\u7d50\u69cb\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b02acc4 e-con-full e-flex e-con e-child\" data-id=\"b02acc4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-df8fa8c elementor-widget thim-widget-button\" data-id=\"df8fa8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a class=\"widget-button normal\" href=\"\/tc\/visitors\/contact-us\/\" target=\"_blank\" rel=\"nofollow\">\u806f\u7d61\u6211\u5011<\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Deparment : Department of Construction, Environment and Engineering Programme Name : Professional Diploma Meister in Power Electrical Engineering Programme Code : ST525108 Duration : Part-time Evening: 2 Years Medium of Instruction : English supplemented with Chinese Venue(s) : THEi Tsing &hellip; <\/p>","protected":false},"author":31,"featured_media":0,"parent":16085,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"ppma_author":[192,171,161,163,151,122,254,262],"class_list":["post-20718","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Professional Diploma Meister Power Electrical Engineering - Technological and Higher Education Institute of Hong Kong<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thei.edu.hk\/tc\/departments\/department-of-construction-environment-and-engineering\/professional-diploma-meister-power-electrical-engineering\/\" \/>\n<meta property=\"og:locale\" content=\"zh_HK\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Professional Diploma Meister Power Electrical Engineering - Technological and Higher Education Institute of Hong Kong\" \/>\n<meta property=\"og:description\" content=\"Deparment : Department of Construction, Environment and Engineering Programme Name : Professional Diploma Meister in Power Electrical Engineering Programme Code : ST525108 Duration : Part-time Evening: 2 Years Medium of Instruction : English supplemented with Chinese Venue(s) : THEi Tsing &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thei.edu.hk\/tc\/departments\/department-of-construction-environment-and-engineering\/professional-diploma-meister-power-electrical-engineering\/\" \/>\n<meta property=\"og:site_name\" content=\"Technological and Higher Education Institute of Hong Kong\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T03:50:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thei.edu.hk\/wp-content\/uploads\/2024\/08\/QF_logo-SVG.svg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u9810\u8a08\u95b1\u8b80\u6642\u9593\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 \u5206\u9418\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thei.edu.hk\\\/tc\\\/departments\\\/department-of-construction-environment-and-engineering\\\/professional-diploma-meister-power-electrical-engineering\\\/\",\"url\":\"https:\\\/\\\/thei.edu.hk\\\/tc\\\/departments\\\/department-of-construction-environment-and-engineering\\\/professional-diploma-meister-power-electrical-engineering\\\/\",\"name\":\"Professional Diploma Meister Power Electrical Engineering - Technological and Higher Education Institute of Hong Kong\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thei.edu.hk\\\/tc\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/thei.edu.hk\\\/tc\\\/departments\\\/department-of-construction-environment-and-engineering\\\/professional-diploma-meister-power-electrical-engineering\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/thei.edu.hk\\\/tc\\\/departments\\\/department-of-construction-environment-and-engineering\\\/professional-diploma-meister-power-electrical-engineering\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thei.edu.hk\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/QF_logo-SVG.svg\",\"datePublished\":\"2024-08-30T09:22:38+00:00\",\"dateModified\":\"2026-05-12T03:50:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thei.edu.hk\\\/tc\\\/departments\\\/department-of-construction-environment-and-engineering\\\/professional-diploma-meister-power-electrical-engineering\\\/#breadcrumb\"},\"inLanguage\":\"zh-HK\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thei.edu.hk\\\/tc\\\/departments\\\/department-of-construction-environment-and-engineering\\\/professional-diploma-meister-power-electrical-engineering\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-HK\",\"@id\":\"https:\\\/\\\/thei.edu.hk\\\/tc\\\/departments\\\/department-of-construction-environment-and-engineering\\\/professional-diploma-meister-power-electrical-engineering\\\/#primaryimage\",\"url\":\"https:\\\/\\\/thei.edu.hk\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/QF_logo-SVG.svg\",\"contentUrl\":\"https:\\\/\\\/thei.edu.hk\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/QF_logo-SVG.svg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thei.edu.hk\\\/tc\\\/departments\\\/department-of-construction-environment-and-engineering\\\/professional-diploma-meister-power-electrical-engineering\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/thei.edu.hk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Departments\",\"item\":\"https:\\\/\\\/thei.edu.hk\\\/tc\\\/departments\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Department of Construction, Environment and Engineering\",\"item\":\"https:\\\/\\\/thei.edu.hk\\\/departments\\\/department-of-construction-environment-and-engineering\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Professional Diploma Meister Power Electrical Engineering\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thei.edu.hk\\\/tc\\\/#website\",\"url\":\"https:\\\/\\\/thei.edu.hk\\\/tc\\\/\",\"name\":\"Technological and Higher Education Institute of Hong Kong\",\"description\":\"Technological and Higher Education Institute of Hong Kong\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thei.edu.hk\\\/tc\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-HK\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Professional Diploma Meister Power Electrical Engineering - Technological and Higher Education Institute of Hong Kong","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thei.edu.hk\/tc\/departments\/department-of-construction-environment-and-engineering\/professional-diploma-meister-power-electrical-engineering\/","og_locale":"zh_HK","og_type":"article","og_title":"Professional Diploma Meister Power Electrical Engineering - Technological and Higher Education Institute of Hong Kong","og_description":"Deparment : Department of Construction, Environment and Engineering Programme Name : Professional Diploma Meister in Power Electrical Engineering Programme Code : ST525108 Duration : Part-time Evening: 2 Years Medium of Instruction : English supplemented with Chinese Venue(s) : THEi Tsing &hellip;","og_url":"https:\/\/thei.edu.hk\/tc\/departments\/department-of-construction-environment-and-engineering\/professional-diploma-meister-power-electrical-engineering\/","og_site_name":"Technological and Higher Education Institute of Hong Kong","article_modified_time":"2026-05-12T03:50:44+00:00","og_image":[{"url":"https:\/\/thei.edu.hk\/wp-content\/uploads\/2024\/08\/QF_logo-SVG.svg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"\u9810\u8a08\u95b1\u8b80\u6642\u9593":"4 \u5206\u9418"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/thei.edu.hk\/tc\/departments\/department-of-construction-environment-and-engineering\/professional-diploma-meister-power-electrical-engineering\/","url":"https:\/\/thei.edu.hk\/tc\/departments\/department-of-construction-environment-and-engineering\/professional-diploma-meister-power-electrical-engineering\/","name":"Professional Diploma Meister Power Electrical Engineering - Technological and Higher Education Institute of Hong Kong","isPartOf":{"@id":"https:\/\/thei.edu.hk\/tc\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thei.edu.hk\/tc\/departments\/department-of-construction-environment-and-engineering\/professional-diploma-meister-power-electrical-engineering\/#primaryimage"},"image":{"@id":"https:\/\/thei.edu.hk\/tc\/departments\/department-of-construction-environment-and-engineering\/professional-diploma-meister-power-electrical-engineering\/#primaryimage"},"thumbnailUrl":"https:\/\/thei.edu.hk\/wp-content\/uploads\/2024\/08\/QF_logo-SVG.svg","datePublished":"2024-08-30T09:22:38+00:00","dateModified":"2026-05-12T03:50:44+00:00","breadcrumb":{"@id":"https:\/\/thei.edu.hk\/tc\/departments\/department-of-construction-environment-and-engineering\/professional-diploma-meister-power-electrical-engineering\/#breadcrumb"},"inLanguage":"zh-HK","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thei.edu.hk\/tc\/departments\/department-of-construction-environment-and-engineering\/professional-diploma-meister-power-electrical-engineering\/"]}]},{"@type":"ImageObject","inLanguage":"zh-HK","@id":"https:\/\/thei.edu.hk\/tc\/departments\/department-of-construction-environment-and-engineering\/professional-diploma-meister-power-electrical-engineering\/#primaryimage","url":"https:\/\/thei.edu.hk\/wp-content\/uploads\/2024\/08\/QF_logo-SVG.svg","contentUrl":"https:\/\/thei.edu.hk\/wp-content\/uploads\/2024\/08\/QF_logo-SVG.svg"},{"@type":"BreadcrumbList","@id":"https:\/\/thei.edu.hk\/tc\/departments\/department-of-construction-environment-and-engineering\/professional-diploma-meister-power-electrical-engineering\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thei.edu.hk\/"},{"@type":"ListItem","position":2,"name":"Departments","item":"https:\/\/thei.edu.hk\/tc\/departments\/"},{"@type":"ListItem","position":3,"name":"Department of Construction, Environment and Engineering","item":"https:\/\/thei.edu.hk\/departments\/department-of-construction-environment-and-engineering\/"},{"@type":"ListItem","position":4,"name":"Professional Diploma Meister Power Electrical Engineering"}]},{"@type":"WebSite","@id":"https:\/\/thei.edu.hk\/tc\/#website","url":"https:\/\/thei.edu.hk\/tc\/","name":"Technological and Higher Education Institute of Hong Kong","description":"Technological and Higher Education Institute of Hong Kong","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thei.edu.hk\/tc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-HK"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 15:41:43","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"author","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/thei.edu.hk\/tc\/wp-json\/wp\/v2\/pages\/20718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thei.edu.hk\/tc\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/thei.edu.hk\/tc\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/thei.edu.hk\/tc\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/thei.edu.hk\/tc\/wp-json\/wp\/v2\/comments?post=20718"}],"version-history":[{"count":4,"href":"https:\/\/thei.edu.hk\/tc\/wp-json\/wp\/v2\/pages\/20718\/revisions"}],"predecessor-version":[{"id":69711,"href":"https:\/\/thei.edu.hk\/tc\/wp-json\/wp\/v2\/pages\/20718\/revisions\/69711"}],"up":[{"embeddable":true,"href":"https:\/\/thei.edu.hk\/tc\/wp-json\/wp\/v2\/pages\/16085"}],"wp:attachment":[{"href":"https:\/\/thei.edu.hk\/tc\/wp-json\/wp\/v2\/media?parent=20718"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/thei.edu.hk\/tc\/wp-json\/wp\/v2\/ppma_author?post=20718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}