{"id":24178,"date":"2024-10-04T00:00:07","date_gmt":"2024-10-03T16:00:07","guid":{"rendered":"https:\/\/thei.hhe-service.com\/?page_id=24178"},"modified":"2026-07-28T16:41:17","modified_gmt":"2026-07-28T08:41:17","slug":"%e7%94%b3%e8%af%b7%e7%a8%8b%e5%ba%8f","status":"publish","type":"page","link":"https:\/\/thei.edu.hk\/tc\/admission\/%e7%94%b3%e8%ab%8b%e5%85%a5%e8%ae%80\/%e7%94%b3%e8%af%b7%e7%a8%8b%e5%ba%8f\/","title":{"rendered":"\u7533\u8bf7\u7a0b\u5e8f"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"24178\" class=\"elementor elementor-24178\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-08c0efe elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"08c0efe\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e9596ad\" data-id=\"e9596ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e899061 elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"e899061\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-293c4a8 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"THEi-TY-Campus-button\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">\u7533\u8bf7\u6d41\u7a0b\u53ca\u91cd\u8981\u65e5\u671f<\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f8db263 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"f8db263\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7dfbc68 university-new\" data-id=\"7dfbc68\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0a70d37 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0a70d37\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b2b546e\" data-id=\"b2b546e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f660eb elementor-widget elementor-widget-thim-single-images\" data-id=\"1f660eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-single-images.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"single-image template-base\"><img fetchpriority=\"high\" decoding=\"async\" width=\"500\" height=\"400\" src=\"https:\/\/thei.edu.hk\/wp-content\/uploads\/2025\/01\/Application-button-11.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/thei.edu.hk\/wp-content\/uploads\/2025\/01\/Application-button-11.jpg 500w, https:\/\/thei.edu.hk\/wp-content\/uploads\/2025\/01\/Application-button-11-400x320.jpg 400w, https:\/\/thei.edu.hk\/wp-content\/uploads\/2025\/01\/Application-button-11-15x12.jpg 15w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-524008f elementor-align-center elementor-widget elementor-widget-button\" data-id=\"524008f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/admission.vtc.edu.hk\/vtcsas\/faces\/login.jspx?sysCode=MS\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u6309\u6b64\u7533\u8bf7<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef906ea iconbox--tablettext-left iconbox-text-left elementor-widget elementor-widget-thim-icon-box\" data-id=\"ef906ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"thim-widget-icon-box\"><div class=\"wrapper-box-icon layout_text_number text-left\"><div class=\"smicon-box iconbox-left\"><div class=\"boxes-icon\"><span class=\"inner-icon\"><span class=\"text-number-icon\">1<\/span><\/span><\/div><div class=\"content-inner\"><div class=\"sc-heading\"><h3 class=\"heading__primary\">\u7f51\u4e0a\u5165\u5b66\u7533\u8bf7<\/h3><\/div><div class=\"desc-icon-box\"><div class=\"desc-content\">\u901a\u8fc7\u7f51\u4e0a\u5165\u5b66\u7533\u8bf7\u7cfb\u7edf\u63d0\u4ea4\u7533\u8bf7\uff0c\u5e76\u4e0a\u4f20\u5b66\u5386\u8bc1\u660e\u53ca\u5176\u4ed6\u76f8\u5173\u6587\u4ef6\u526f\u672c\u3002\n\u4e00\u5e74\u7ea7\u5165\u5b66\u7533\u8bf7\u987b\u901a\u8fc7\u7f51\u4e0a\u652f\u4ed8\u5e73\u53f0\u4ee5\u94f6\u8054\uff0c\u652f\u4ed8\u5b9d\u6216\u5fae\u4fe1\u652f\u4ed8\u7f34\u4ed8\u7533\u8bf7\u8d39\u6e2f\u5e01600\u5143\u3002<\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6e1db7 iconbox--tablettext-left iconbox-text-left elementor-widget elementor-widget-thim-icon-box\" data-id=\"d6e1db7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"thim-widget-icon-box\"><div class=\"wrapper-box-icon layout_text_number text-left\"><div class=\"smicon-box iconbox-left\"><div class=\"boxes-icon\"><span class=\"inner-icon\"><span class=\"text-number-icon\">2<\/span><\/span><\/div><div class=\"content-inner\"><div class=\"sc-heading\"><h3 class=\"heading__primary\">\u622a\u6b62\u7533\u8bf7\u65e5\u671f<\/h3><\/div><div class=\"desc-icon-box\"><div class=\"desc-content\">\u4ee5\u5e94\u5c4a\u9ad8\u8003\u6210\u7ee9\u7533\u8bf7\u5165\u8bfb\u4e00\u5e74\u7ea7\uff1a 2026\u5e746\u670825\u65e5<br>\u4ee5\u5176\u4ed6\u5b66\u5386\u7533\u8bf7\u5165\u8bfb\u4e00\u5e74\u7ea7\uff1a2026\u5e747\u670831\u65e5\u3002<\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-848ba4f iconbox--tablettext-left iconbox-text-left elementor-widget elementor-widget-thim-icon-box\" data-id=\"848ba4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"thim-widget-icon-box\"><div class=\"wrapper-box-icon layout_text_number text-left\"><div class=\"smicon-box iconbox-left\"><div class=\"boxes-icon\"><span class=\"inner-icon\"><span class=\"text-number-icon\">3<\/span><\/span><\/div><div class=\"content-inner\"><div class=\"sc-heading\"><h3 class=\"heading__primary\">\u516c\u5e03\u5f55\u53d6\u901a\u77e5<\/h3><\/div><div class=\"desc-icon-box\"><div class=\"desc-content\">\u4ee5\u5e94\u5c4a\u9ad8\u8003\u6210\u7ee9\u7533\u8bf7\u5165\u8bfb\u4e00\u5e74\u7ea7\uff1a2026\u5e746\u6708\u5e95\u81f37\u67087\u65e5*<br>\u4ee5\u5176\u4ed6\u5b66\u5386\u7533\u8bf7\u5165\u8bfb\u4e00\u5e74\u7ea7\uff1a\u4e0d\u8fdf\u4e8e2026\u5e748\u6708(\u5f85\u5b9a)<br><i>* \u4e0d\u540c\u7701\u5e02\u7684\u6295\u6863\u65e5\u671f\u53ca\u5b89\u6392\u5404\u6709\u4e0d\u540c\uff0c\u76f8\u5173\u5177\u4f53\u6d41\u7a0b\u5c06\u4f9d\u636e\u6559\u80b2\u90e8\u5ba3\u5e03\u4e4b\u9ad8\u8003\u53ca\u5f55\u53d6\u653f\u7b56\u4f5c\u51fa\u53ca\u65f6\u8c03\u6574\u3002\u5b66\u9662\u4ea6\u4f1a\u6839\u636e\u5b9e\u9645\u5f55\u53d6\u60c5\u51b5\u800c\u63d0\u524d\u7ed3\u675f\u5f55\u53d6\u5de5\u4f5c\u3002<\/i>\n<\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0a0ab1 iconbox--tablettext-left iconbox-text-left elementor-widget elementor-widget-thim-icon-box\" data-id=\"d0a0ab1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"thim-widget-icon-box\"><div class=\"wrapper-box-icon layout_text_number text-left\"><div class=\"smicon-box iconbox-left\"><div class=\"boxes-icon\"><span class=\"inner-icon\"><span class=\"text-number-icon\">4<\/span><\/span><\/div><div class=\"content-inner\"><div class=\"sc-heading\"><h3 class=\"heading__primary\">\u5165\u5b66\u6ce8\u518c\u53ca\u8fce\u65b0\u6d3b\u52a8<\/h3><\/div><div class=\"desc-icon-box\"><div class=\"desc-content\">\u83b7\u5f55\u53d6\u7684\u540c\u5b66\u8bf7\u65bc8\u6708\u4e0b\u65ec\u81f3 9 \u6708\u521d(\u6682\u5b9a)\u6765\u6e2f\u6ce8\u518c\u5165\u5b66\u53ca\u53c2\u52a0\u8fce\u65b0\u6d3b\u52a8\u3002\u5b66\u751f\u987b\u5728\u5f55\u53d6\u901a\u77e5\u4e66\u7684\u6307\u5b9a\u9650\u671f\u524d, \u6309\u7f34\u8d39\u901a\u77e5\u4e66\u7684\u6307\u793a\u7f34\u4ed8\u7b2c\u4e00\u671f\u5b66\u8d39\u53ca\u5b66\u751f\u670d\u52a1\u8d39\u7b49\u8d39\u7528\u3002<\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8584607 elementor-widget elementor-widget-text-editor\" data-id=\"8584607\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>\u7533\u8bf7\u4eba\u5982\u57282026\u5e741\u670831\u65e5\u6216\u4e4b\u524d\u63d0\u4ea4\u7533\u8bf7\uff0c\u5373\u53ef\u4ee5\u65e9\u9e1f\u4f18\u60e0\u4ef7\u6e2f\u5e01300\u5143\u7533\u8bf7\u4e00\u5e74\u7ea7\u5165\u5b66\uff1b\u5728\u6b64\u65e5\u671f\u540e\u63d0\u4ea4\uff0c\u7533\u8bf7\u8d39\u4e3a\u6e2f\u5e01600\u5143\u3002<\/li><li>\u5185\u573031\u4e2a\u7701\u4efd\u3001\u81ea\u6cbb\u533a\u53ca\u76f4\u8f96\u5e02\u7684\u5e94\u5c4a\u9ad8\u8003\u751f\u5747\u53ef\u7533\u8bf7THEi\u9ad8\u79d1\u9662\u672c\u79d1\u5165\u5b66\u3002\u5831\u8bfbTHEi\u9ad8\u79d1\u9662\u4e0d\u5360\u300c\u5168\u56fd\u666e\u901a\u9ad8\u6821\u7edf\u4e00\u62db\u751f\u8ba1\u5212\u300d\uff08\u7edf\u62db\uff09\u5fd7\u613f\u3002\u6839\u636e\u56fd\u5bb6\u6559\u80b2\u90e8\u89c4\u5b9a\uff0c\u5185\u5730\u5b66\u751f\u82e5\u83b7\u5f97\u9ad8\u79d1\u9662\u5f55\u53d6\u5e76\u63a5\u7eb3\u6709\u5173\u5b66\u7c4d\uff0c\u5185\u5730\u7edf\u62db\u9ad8\u6821\u5c06\u4e0d\u518d\u4e88\u4ee5\u5f55\u53d6\u3002<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-815db9b\" data-id=\"815db9b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a559e4e elementor-widget elementor-widget-thim-single-images\" data-id=\"a559e4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-single-images.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"single-image template-base\"><img decoding=\"async\" width=\"500\" height=\"400\" src=\"https:\/\/thei.edu.hk\/wp-content\/uploads\/2025\/01\/Application-button-21.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/thei.edu.hk\/wp-content\/uploads\/2025\/01\/Application-button-21.jpg 500w, https:\/\/thei.edu.hk\/wp-content\/uploads\/2025\/01\/Application-button-21-400x320.jpg 400w, https:\/\/thei.edu.hk\/wp-content\/uploads\/2025\/01\/Application-button-21-15x12.jpg 15w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce3f9b3 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"ce3f9b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/admission.vtc.edu.hk\/vtcsas\/faces\/login.jspx?sysCode=MS\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u6309\u6b64\u7533\u8bf7<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a844361 iconbox--tablettext-left iconbox-text-left elementor-widget elementor-widget-thim-icon-box\" data-id=\"a844361\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"thim-widget-icon-box\"><div class=\"wrapper-box-icon layout_text_number text-left\"><div class=\"smicon-box iconbox-left\"><div class=\"boxes-icon\"><span class=\"inner-icon\"><span class=\"text-number-icon\">1<\/span><\/span><\/div><div class=\"content-inner\"><div class=\"sc-heading\"><h3 class=\"heading__primary\">\u7f51\u4e0a\u5165\u5b66\u7533\u8bf7<\/h3><\/div><div class=\"desc-icon-box\"><div class=\"desc-content\">\u901a\u8fc7\u7f51\u4e0a\u5165\u5b66\u7533\u8bf7\u7cfb\u7edf\u63d0\u4ea4\u7533\u8bf7\uff0c\u5e76\u4e0a\u4f20\u5b66\u5386\u8bc1\u660e\uff0c<strong><font color=\"red\">\u8bfe\u7a0b\u5927\u7eb2<\/font><\/strong>\u53ca\u5176\u4ed6\u76f8\u5173\u6587\u4ef6\u526f\u672c\u3002\n\u4e8c\u3001\u4e09\u5e74\u7ea7\u5165\u5b66\u7533\u8bf7\u65e0\u987b\u7e73\u4ea4\u7533\u8bf7\u8d39\u3002<\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5df21f4 iconbox--tablettext-left iconbox-text-left elementor-widget elementor-widget-thim-icon-box\" data-id=\"5df21f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"thim-widget-icon-box\"><div class=\"wrapper-box-icon layout_text_number text-left\"><div class=\"smicon-box iconbox-left\"><div class=\"boxes-icon\"><span class=\"inner-icon\"><span class=\"text-number-icon\">2<\/span><\/span><\/div><div class=\"content-inner\"><div class=\"sc-heading\"><h3 class=\"heading__primary\">\u622a\u6b62\u7533\u8bf7\u65e5\u671f<\/h3><\/div><div class=\"desc-icon-box\"><div class=\"desc-content\">\u7533\u8bf7\u4e8c\u53ca\u4e09\u5e74\u7ea7\u5165\u5b66\uff1a<br> 2026\u5e747\u670831\u65e5<\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d205be iconbox--tablettext-left iconbox-text-left elementor-widget elementor-widget-thim-icon-box\" data-id=\"8d205be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"thim-widget-icon-box\"><div class=\"wrapper-box-icon layout_text_number text-left\"><div class=\"smicon-box iconbox-left\"><div class=\"boxes-icon\"><span class=\"inner-icon\"><span class=\"text-number-icon\">3<\/span><\/span><\/div><div class=\"content-inner\"><div class=\"sc-heading\"><h3 class=\"heading__primary\">\u516c\u5e03\u5f55\u53d6\u901a\u77e5<\/h3><\/div><div class=\"desc-icon-box\"><div class=\"desc-content\">\u4e0d\u8fdf\u4e8e2026\u5e748\u6708(\u5f85\u5b9a)<\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47cb329 iconbox--tablettext-left iconbox-text-left elementor-widget elementor-widget-thim-icon-box\" data-id=\"47cb329\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"thim-widget-icon-box\"><div class=\"wrapper-box-icon layout_text_number text-left\"><div class=\"smicon-box iconbox-left\"><div class=\"boxes-icon\"><span class=\"inner-icon\"><span class=\"text-number-icon\">4<\/span><\/span><\/div><div class=\"content-inner\"><div class=\"sc-heading\"><h3 class=\"heading__primary\">\u5165\u5b66\u6ce8\u518c\u53ca\u8fce\u65b0\u6d3b\u52a8<\/h3><\/div><div class=\"desc-icon-box\"><div class=\"desc-content\">\u83b7\u5f55\u53d6\u7684\u540c\u5b66\u8bf7\u65bc8\u6708\u4e0b\u65ec\u81f3 9 \u6708\u521d(\u6682\u5b9a)\u6765\u6e2f\u6ce8\u518c\u5165\u5b66\u53ca\u53c2\u52a0\u8fce\u65b0\u6d3b\u52a8\u3002\u5b66\u751f\u987b\u5728\u5f55\u53d6\u901a\u77e5\u4e66\u7684\u6307\u5b9a\u9650\u671f\u524d, \u6309\u7f34\u8d39\u901a\u77e5\u4e66\u7684\u6307\u793a\u7f34\u4ed8\u7b2c\u4e00\u671f\u5b66\u8d39\u53ca\u5b66\u751f\u670d\u52a1\u8d39\u7b49\u8d39\u7528\u3002<\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2c80fef\" data-id=\"2c80fef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d6e1a6 elementor-widget elementor-widget-thim-single-images\" data-id=\"9d6e1a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-single-images.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"single-image template-base\"><img decoding=\"async\" width=\"500\" height=\"400\" src=\"https:\/\/thei.edu.hk\/wp-content\/uploads\/2025\/01\/Application-button-31.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/thei.edu.hk\/wp-content\/uploads\/2025\/01\/Application-button-31.jpg 500w, https:\/\/thei.edu.hk\/wp-content\/uploads\/2025\/01\/Application-button-31-400x320.jpg 400w, https:\/\/thei.edu.hk\/wp-content\/uploads\/2025\/01\/Application-button-31-15x12.jpg 15w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc3a7bf elementor-align-center elementor-widget elementor-widget-button\" data-id=\"bc3a7bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/admission.vtc.edu.hk\/vtcsas\/faces\/login.jspx?sysCode=MS\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u6309\u6b64\u7533\u8bf7<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc2618e iconbox--tablettext-left iconbox-text-left elementor-widget elementor-widget-thim-icon-box\" data-id=\"dc2618e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"thim-widget-icon-box\"><div class=\"wrapper-box-icon layout_text_number text-left\"><div class=\"smicon-box iconbox-left\"><div class=\"boxes-icon\"><span class=\"inner-icon\"><span class=\"text-number-icon\">1<\/span><\/span><\/div><div class=\"content-inner\"><div class=\"sc-heading\"><h3 class=\"heading__primary\">\u7f51\u4e0a\u5165\u5b66\u7533\u8bf7<\/h3><\/div><div class=\"desc-icon-box\"><div class=\"desc-content\">\u901a\u8fc7\u7f51\u4e0a\u5165\u5b66\u7533\u8bf7\u7cfb\u7edf\u63d0\u4ea4\u7533\u8bf7\uff0c\u5e76\u4e0a\u4f20\u5b66\u5386\u8bc1\u660e\u53ca\u5176\u4ed6\u76f8\u5173\u6587\u4ef6\u526f\u672c\u3002\n\u7533\u8bf7\u987b\u901a\u8fc7\u7f51\u4e0a\u652f\u4ed8\u5e73\u53f0\u4ee5\u94f6\u8054\u6216\u652f\u4ed8\u5b9d\u7f34\u4ed8\u7533\u8bf7\u8d39\u6e2f\u5e011,000\u5143\u3002<\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-80484db iconbox--tablettext-left iconbox-text-left elementor-widget elementor-widget-thim-icon-box\" data-id=\"80484db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"thim-widget-icon-box\"><div class=\"wrapper-box-icon layout_text_number text-left\"><div class=\"smicon-box iconbox-left\"><div class=\"boxes-icon\"><span class=\"inner-icon\"><span class=\"text-number-icon\">2<\/span><\/span><\/div><div class=\"content-inner\"><div class=\"sc-heading\"><h3 class=\"heading__primary\">\u622a\u6b62\u7533\u8bf7\u65e5\u671f<\/h3><\/div><div class=\"desc-icon-box\"><div class=\"desc-content\"> 2026\u5e749\u670830\u65e5<\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17f1d57 iconbox--tablettext-left iconbox-text-left elementor-widget elementor-widget-thim-icon-box\" data-id=\"17f1d57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"thim-widget-icon-box\"><div class=\"wrapper-box-icon layout_text_number text-left\"><div class=\"smicon-box iconbox-left\"><div class=\"boxes-icon\"><span class=\"inner-icon\"><span class=\"text-number-icon\">3<\/span><\/span><\/div><div class=\"content-inner\"><div class=\"sc-heading\"><h3 class=\"heading__primary\">\u516c\u5e03\u5f55\u53d6\u901a\u77e5<\/h3><\/div><div class=\"desc-icon-box\"><div class=\"desc-content\">\u4e0d\u8fdf\u4e8e2026\u5e7410\u6708(\u5f85\u5b9a)<\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff53358 iconbox--tablettext-left iconbox-text-left elementor-widget elementor-widget-thim-icon-box\" data-id=\"ff53358\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"thim-widget-icon-box\"><div class=\"wrapper-box-icon layout_text_number text-left\"><div class=\"smicon-box iconbox-left\"><div class=\"boxes-icon\"><span class=\"inner-icon\"><span class=\"text-number-icon\">4<\/span><\/span><\/div><div class=\"content-inner\"><div class=\"sc-heading\"><h3 class=\"heading__primary\">\u5165\u5b66\u6ce8\u518c\u53ca\u8fce\u65b0\u6d3b\u52a8<\/h3><\/div><div class=\"desc-icon-box\"><div class=\"desc-content\">\u5b66\u751f\u987b\u5728\u5f55\u53d6\u901a\u77e5\u4e66\u7684\u6307\u5b9a\u9650\u671f\u524d, \u6309\u7f34\u8d39\u901a\u77e5\u4e66\u7684\u6307\u793a\u7f34\u4ed8\u7b2c\u4e00\u671f\u5b66\u8d39\u53ca\u5b66\u751f\u670d\u52a1\u8d39\u7b49\u8d39\u7528\u3002<\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u7533\u8bf7\u6d41\u7a0b\u53ca\u91cd\u8981\u65e5\u671f \u6309\u6b64\u7533\u8bf7 1 \u7f51\u4e0a\u5165\u5b66\u7533\u8bf7 \u901a\u8fc7\u7f51\u4e0a\u5165\u5b66\u7533\u8bf7\u7cfb\u7edf\u63d0\u4ea4\u7533\u8bf7\uff0c\u5e76\u4e0a\u4f20\u5b66\u5386\u8bc1\u660e\u53ca\u5176\u4ed6\u76f8\u5173\u6587\u4ef6\u526f\u672c\u3002 \u4e00\u5e74\u7ea7\u5165\u5b66\u7533\u8bf7\u987b\u901a\u8fc7\u7f51\u4e0a\u652f\u4ed8\u5e73\u53f0\u4ee5\u94f6\u8054\uff0c\u652f\u4ed8\u5b9d\u6216\u5fae\u4fe1\u652f\u4ed8\u7f34\u4ed8\u7533\u8bf7\u8d39\u6e2f\u5e01600\u5143\u3002 2 \u622a\u6b62\u7533\u8bf7\u65e5\u671f \u4ee5\u5e94\u5c4a\u9ad8\u8003\u6210\u7ee9\u7533\u8bf7\u5165\u8bfb\u4e00\u5e74\u7ea7\uff1a 2026\u5e746\u670825\u65e5\u4ee5\u5176\u4ed6\u5b66\u5386\u7533\u8bf7\u5165\u8bfb\u4e00\u5e74\u7ea7\uff1a2026\u5e747\u670831\u65e5\u3002 3 \u516c\u5e03\u5f55\u53d6\u901a\u77e5 \u4ee5\u5e94\u5c4a\u9ad8\u8003\u6210\u7ee9\u7533\u8bf7\u5165\u8bfb\u4e00\u5e74\u7ea7\uff1a2026\u5e746\u6708\u5e95\u81f37\u67087\u65e5*\u4ee5\u5176\u4ed6\u5b66\u5386\u7533\u8bf7\u5165\u8bfb\u4e00\u5e74\u7ea7\uff1a\u4e0d\u8fdf\u4e8e2026\u5e748\u6708(\u5f85\u5b9a)* \u4e0d\u540c\u7701\u5e02\u7684\u6295\u6863\u65e5\u671f\u53ca\u5b89\u6392\u5404\u6709\u4e0d\u540c\uff0c\u76f8\u5173\u5177\u4f53\u6d41\u7a0b\u5c06\u4f9d\u636e\u6559\u80b2\u90e8\u5ba3\u5e03\u4e4b\u9ad8\u8003\u53ca\u5f55\u53d6\u653f\u7b56\u4f5c\u51fa\u53ca\u65f6\u8c03\u6574\u3002\u5b66\u9662\u4ea6\u4f1a\u6839\u636e\u5b9e\u9645\u5f55\u53d6\u60c5\u51b5\u800c\u63d0\u524d\u7ed3\u675f\u5f55\u53d6\u5de5\u4f5c\u3002 4 \u5165\u5b66\u6ce8\u518c\u53ca\u8fce\u65b0\u6d3b\u52a8 \u83b7\u5f55\u53d6\u7684\u540c\u5b66\u8bf7\u65bc8\u6708\u4e0b\u65ec\u81f3 9 \u6708\u521d(\u6682\u5b9a)\u6765\u6e2f\u6ce8\u518c\u5165\u5b66\u53ca\u53c2\u52a0\u8fce\u65b0\u6d3b\u52a8\u3002\u5b66\u751f\u987b\u5728\u5f55\u53d6\u901a\u77e5\u4e66\u7684\u6307\u5b9a\u9650\u671f\u524d, \u6309\u7f34\u8d39\u901a\u77e5\u4e66\u7684\u6307\u793a\u7f34\u4ed8\u7b2c\u4e00\u671f\u5b66\u8d39\u53ca\u5b66\u751f\u670d\u52a1\u8d39\u7b49\u8d39\u7528\u3002 \u7533\u8bf7\u4eba\u5982\u57282026\u5e741\u670831\u65e5\u6216\u4e4b\u524d\u63d0\u4ea4\u7533\u8bf7\uff0c\u5373\u53ef\u4ee5\u65e9\u9e1f\u4f18\u60e0\u4ef7\u6e2f\u5e01300\u5143\u7533\u8bf7\u4e00\u5e74\u7ea7\u5165\u5b66\uff1b\u5728\u6b64\u65e5\u671f\u540e\u63d0\u4ea4\uff0c\u7533\u8bf7\u8d39\u4e3a\u6e2f\u5e01600\u5143\u3002 \u5185\u573031\u4e2a\u7701\u4efd\u3001\u81ea\u6cbb\u533a\u53ca\u76f4\u8f96\u5e02\u7684\u5e94\u5c4a\u9ad8\u8003\u751f\u5747\u53ef\u7533\u8bf7THEi\u9ad8\u79d1\u9662\u672c\u79d1\u5165\u5b66\u3002\u5831\u8bfbTHEi\u9ad8\u79d1\u9662\u4e0d\u5360\u300c\u5168\u56fd\u666e\u901a\u9ad8\u6821\u7edf\u4e00\u62db\u751f\u8ba1\u5212\u300d\uff08\u7edf\u62db\uff09\u5fd7\u613f\u3002\u6839\u636e\u56fd\u5bb6\u6559\u80b2\u90e8\u89c4\u5b9a\uff0c\u5185\u5730\u5b66\u751f\u82e5\u83b7\u5f97\u9ad8\u79d1\u9662\u5f55\u53d6\u5e76\u63a5\u7eb3\u6709\u5173\u5b66\u7c4d\uff0c\u5185\u5730\u7edf\u62db\u9ad8\u6821\u5c06\u4e0d\u518d\u4e88\u4ee5\u5f55\u53d6\u3002 \u6309\u6b64\u7533\u8bf7 1 \u7f51\u4e0a\u5165\u5b66\u7533\u8bf7 \u901a\u8fc7\u7f51\u4e0a\u5165\u5b66\u7533\u8bf7\u7cfb\u7edf\u63d0\u4ea4\u7533\u8bf7\uff0c\u5e76\u4e0a\u4f20\u5b66\u5386\u8bc1\u660e\uff0c\u8bfe\u7a0b\u5927\u7eb2\u53ca\u5176\u4ed6\u76f8\u5173\u6587\u4ef6\u526f\u672c\u3002 \u4e8c\u3001\u4e09\u5e74\u7ea7\u5165\u5b66\u7533\u8bf7\u65e0\u987b\u7e73\u4ea4\u7533\u8bf7\u8d39\u3002 2 \u622a\u6b62\u7533\u8bf7\u65e5\u671f \u7533\u8bf7\u4e8c\u53ca\u4e09\u5e74\u7ea7\u5165\u5b66\uff1a 2026\u5e747\u670831\u65e5 3 \u516c\u5e03\u5f55\u53d6\u901a\u77e5 \u4e0d\u8fdf\u4e8e2026\u5e748\u6708(\u5f85\u5b9a) 4 \u5165\u5b66\u6ce8\u518c\u53ca\u8fce\u65b0\u6d3b\u52a8 \u83b7\u5f55\u53d6\u7684\u540c\u5b66\u8bf7\u65bc8\u6708\u4e0b\u65ec\u81f3 9 \u6708\u521d(\u6682\u5b9a)\u6765\u6e2f\u6ce8\u518c\u5165\u5b66\u53ca\u53c2\u52a0\u8fce\u65b0\u6d3b\u52a8\u3002\u5b66\u751f\u987b\u5728\u5f55\u53d6\u901a\u77e5\u4e66\u7684\u6307\u5b9a\u9650\u671f\u524d, \u6309\u7f34\u8d39\u901a\u77e5\u4e66\u7684\u6307\u793a\u7f34\u4ed8\u7b2c\u4e00\u671f\u5b66\u8d39\u53ca\u5b66\u751f\u670d\u52a1\u8d39\u7b49\u8d39\u7528\u3002 &hellip; <\/p>","protected":false},"author":77,"featured_media":0,"parent":24170,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"ppma_author":[186,190,177,169,127,156,164,180,157,128,167,119,170,162,166,259],"class_list":["post-24178","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u7533\u8bf7\u7a0b\u5e8f - Technological and Higher Education Institute of Hong Kong<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thei.edu.hk\/tc\/admission\/\u7533\u8acb\u5165\u8b80\/\u7533\u8bf7\u7a0b\u5e8f\/\" \/>\n<meta property=\"og:locale\" content=\"zh_HK\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u7533\u8bf7\u7a0b\u5e8f - Technological and Higher Education Institute of Hong Kong\" \/>\n<meta property=\"og:description\" content=\"\u7533\u8bf7\u6d41\u7a0b\u53ca\u91cd\u8981\u65e5\u671f \u6309\u6b64\u7533\u8bf7 1 \u7f51\u4e0a\u5165\u5b66\u7533\u8bf7 \u901a\u8fc7\u7f51\u4e0a\u5165\u5b66\u7533\u8bf7\u7cfb\u7edf\u63d0\u4ea4\u7533\u8bf7\uff0c\u5e76\u4e0a\u4f20\u5b66\u5386\u8bc1\u660e\u53ca\u5176\u4ed6\u76f8\u5173\u6587\u4ef6\u526f\u672c\u3002 \u4e00\u5e74\u7ea7\u5165\u5b66\u7533\u8bf7\u987b\u901a\u8fc7\u7f51\u4e0a\u652f\u4ed8\u5e73\u53f0\u4ee5\u94f6\u8054\uff0c\u652f\u4ed8\u5b9d\u6216\u5fae\u4fe1\u652f\u4ed8\u7f34\u4ed8\u7533\u8bf7\u8d39\u6e2f\u5e01600\u5143\u3002 2 \u622a\u6b62\u7533\u8bf7\u65e5\u671f \u4ee5\u5e94\u5c4a\u9ad8\u8003\u6210\u7ee9\u7533\u8bf7\u5165\u8bfb\u4e00\u5e74\u7ea7\uff1a 2026\u5e746\u670825\u65e5\u4ee5\u5176\u4ed6\u5b66\u5386\u7533\u8bf7\u5165\u8bfb\u4e00\u5e74\u7ea7\uff1a2026\u5e747\u670831\u65e5\u3002 3 \u516c\u5e03\u5f55\u53d6\u901a\u77e5 \u4ee5\u5e94\u5c4a\u9ad8\u8003\u6210\u7ee9\u7533\u8bf7\u5165\u8bfb\u4e00\u5e74\u7ea7\uff1a2026\u5e746\u6708\u5e95\u81f37\u67087\u65e5*\u4ee5\u5176\u4ed6\u5b66\u5386\u7533\u8bf7\u5165\u8bfb\u4e00\u5e74\u7ea7\uff1a\u4e0d\u8fdf\u4e8e2026\u5e748\u6708(\u5f85\u5b9a)* \u4e0d\u540c\u7701\u5e02\u7684\u6295\u6863\u65e5\u671f\u53ca\u5b89\u6392\u5404\u6709\u4e0d\u540c\uff0c\u76f8\u5173\u5177\u4f53\u6d41\u7a0b\u5c06\u4f9d\u636e\u6559\u80b2\u90e8\u5ba3\u5e03\u4e4b\u9ad8\u8003\u53ca\u5f55\u53d6\u653f\u7b56\u4f5c\u51fa\u53ca\u65f6\u8c03\u6574\u3002\u5b66\u9662\u4ea6\u4f1a\u6839\u636e\u5b9e\u9645\u5f55\u53d6\u60c5\u51b5\u800c\u63d0\u524d\u7ed3\u675f\u5f55\u53d6\u5de5\u4f5c\u3002 4 \u5165\u5b66\u6ce8\u518c\u53ca\u8fce\u65b0\u6d3b\u52a8 \u83b7\u5f55\u53d6\u7684\u540c\u5b66\u8bf7\u65bc8\u6708\u4e0b\u65ec\u81f3 9 \u6708\u521d(\u6682\u5b9a)\u6765\u6e2f\u6ce8\u518c\u5165\u5b66\u53ca\u53c2\u52a0\u8fce\u65b0\u6d3b\u52a8\u3002\u5b66\u751f\u987b\u5728\u5f55\u53d6\u901a\u77e5\u4e66\u7684\u6307\u5b9a\u9650\u671f\u524d, \u6309\u7f34\u8d39\u901a\u77e5\u4e66\u7684\u6307\u793a\u7f34\u4ed8\u7b2c\u4e00\u671f\u5b66\u8d39\u53ca\u5b66\u751f\u670d\u52a1\u8d39\u7b49\u8d39\u7528\u3002 \u7533\u8bf7\u4eba\u5982\u57282026\u5e741\u670831\u65e5\u6216\u4e4b\u524d\u63d0\u4ea4\u7533\u8bf7\uff0c\u5373\u53ef\u4ee5\u65e9\u9e1f\u4f18\u60e0\u4ef7\u6e2f\u5e01300\u5143\u7533\u8bf7\u4e00\u5e74\u7ea7\u5165\u5b66\uff1b\u5728\u6b64\u65e5\u671f\u540e\u63d0\u4ea4\uff0c\u7533\u8bf7\u8d39\u4e3a\u6e2f\u5e01600\u5143\u3002 \u5185\u573031\u4e2a\u7701\u4efd\u3001\u81ea\u6cbb\u533a\u53ca\u76f4\u8f96\u5e02\u7684\u5e94\u5c4a\u9ad8\u8003\u751f\u5747\u53ef\u7533\u8bf7THEi\u9ad8\u79d1\u9662\u672c\u79d1\u5165\u5b66\u3002\u5831\u8bfbTHEi\u9ad8\u79d1\u9662\u4e0d\u5360\u300c\u5168\u56fd\u666e\u901a\u9ad8\u6821\u7edf\u4e00\u62db\u751f\u8ba1\u5212\u300d\uff08\u7edf\u62db\uff09\u5fd7\u613f\u3002\u6839\u636e\u56fd\u5bb6\u6559\u80b2\u90e8\u89c4\u5b9a\uff0c\u5185\u5730\u5b66\u751f\u82e5\u83b7\u5f97\u9ad8\u79d1\u9662\u5f55\u53d6\u5e76\u63a5\u7eb3\u6709\u5173\u5b66\u7c4d\uff0c\u5185\u5730\u7edf\u62db\u9ad8\u6821\u5c06\u4e0d\u518d\u4e88\u4ee5\u5f55\u53d6\u3002 \u6309\u6b64\u7533\u8bf7 1 \u7f51\u4e0a\u5165\u5b66\u7533\u8bf7 \u901a\u8fc7\u7f51\u4e0a\u5165\u5b66\u7533\u8bf7\u7cfb\u7edf\u63d0\u4ea4\u7533\u8bf7\uff0c\u5e76\u4e0a\u4f20\u5b66\u5386\u8bc1\u660e\uff0c\u8bfe\u7a0b\u5927\u7eb2\u53ca\u5176\u4ed6\u76f8\u5173\u6587\u4ef6\u526f\u672c\u3002 \u4e8c\u3001\u4e09\u5e74\u7ea7\u5165\u5b66\u7533\u8bf7\u65e0\u987b\u7e73\u4ea4\u7533\u8bf7\u8d39\u3002 2 \u622a\u6b62\u7533\u8bf7\u65e5\u671f \u7533\u8bf7\u4e8c\u53ca\u4e09\u5e74\u7ea7\u5165\u5b66\uff1a 2026\u5e747\u670831\u65e5 3 \u516c\u5e03\u5f55\u53d6\u901a\u77e5 \u4e0d\u8fdf\u4e8e2026\u5e748\u6708(\u5f85\u5b9a) 4 \u5165\u5b66\u6ce8\u518c\u53ca\u8fce\u65b0\u6d3b\u52a8 \u83b7\u5f55\u53d6\u7684\u540c\u5b66\u8bf7\u65bc8\u6708\u4e0b\u65ec\u81f3 9 \u6708\u521d(\u6682\u5b9a)\u6765\u6e2f\u6ce8\u518c\u5165\u5b66\u53ca\u53c2\u52a0\u8fce\u65b0\u6d3b\u52a8\u3002\u5b66\u751f\u987b\u5728\u5f55\u53d6\u901a\u77e5\u4e66\u7684\u6307\u5b9a\u9650\u671f\u524d, \u6309\u7f34\u8d39\u901a\u77e5\u4e66\u7684\u6307\u793a\u7f34\u4ed8\u7b2c\u4e00\u671f\u5b66\u8d39\u53ca\u5b66\u751f\u670d\u52a1\u8d39\u7b49\u8d39\u7528\u3002 &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thei.edu.hk\/tc\/admission\/\u7533\u8acb\u5165\u8b80\/\u7533\u8bf7\u7a0b\u5e8f\/\" \/>\n<meta property=\"og:site_name\" content=\"Technological and Higher Education Institute of Hong Kong\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-28T08:41:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thei.edu.hk\/wp-content\/uploads\/2025\/01\/Application-button-11.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u9810\u8a08\u95b1\u8b80\u6642\u9593\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 \u5206\u9418\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thei.edu.hk\\\/tc\\\/admission\\\/%e7%94%b3%e8%ab%8b%e5%85%a5%e8%ae%80\\\/%e7%94%b3%e8%af%b7%e7%a8%8b%e5%ba%8f\\\/\",\"url\":\"https:\\\/\\\/thei.edu.hk\\\/tc\\\/admission\\\/%e7%94%b3%e8%ab%8b%e5%85%a5%e8%ae%80\\\/%e7%94%b3%e8%af%b7%e7%a8%8b%e5%ba%8f\\\/\",\"name\":\"\u7533\u8bf7\u7a0b\u5e8f - Technological and Higher Education Institute of Hong Kong\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thei.edu.hk\\\/tc\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/thei.edu.hk\\\/tc\\\/admission\\\/%e7%94%b3%e8%ab%8b%e5%85%a5%e8%ae%80\\\/%e7%94%b3%e8%af%b7%e7%a8%8b%e5%ba%8f\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/thei.edu.hk\\\/tc\\\/admission\\\/%e7%94%b3%e8%ab%8b%e5%85%a5%e8%ae%80\\\/%e7%94%b3%e8%af%b7%e7%a8%8b%e5%ba%8f\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thei.edu.hk\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Application-button-11.jpg\",\"datePublished\":\"2024-10-03T16:00:07+00:00\",\"dateModified\":\"2026-07-28T08:41:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thei.edu.hk\\\/tc\\\/admission\\\/%e7%94%b3%e8%ab%8b%e5%85%a5%e8%ae%80\\\/%e7%94%b3%e8%af%b7%e7%a8%8b%e5%ba%8f\\\/#breadcrumb\"},\"inLanguage\":\"zh-HK\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thei.edu.hk\\\/tc\\\/admission\\\/%e7%94%b3%e8%ab%8b%e5%85%a5%e8%ae%80\\\/%e7%94%b3%e8%af%b7%e7%a8%8b%e5%ba%8f\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-HK\",\"@id\":\"https:\\\/\\\/thei.edu.hk\\\/tc\\\/admission\\\/%e7%94%b3%e8%ab%8b%e5%85%a5%e8%ae%80\\\/%e7%94%b3%e8%af%b7%e7%a8%8b%e5%ba%8f\\\/#primaryimage\",\"url\":\"https:\\\/\\\/thei.edu.hk\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Application-button-11.jpg\",\"contentUrl\":\"https:\\\/\\\/thei.edu.hk\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Application-button-11.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thei.edu.hk\\\/tc\\\/admission\\\/%e7%94%b3%e8%ab%8b%e5%85%a5%e8%ae%80\\\/%e7%94%b3%e8%af%b7%e7%a8%8b%e5%ba%8f\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/thei.edu.hk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Admission\",\"item\":\"https:\\\/\\\/thei.edu.hk\\\/admission\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u7533\u8acb\u5165\u8b80\",\"item\":\"https:\\\/\\\/thei.edu.hk\\\/admission\\\/%e7%94%b3%e8%ab%8b%e5%85%a5%e8%ae%80\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u7533\u8bf7\u7a0b\u5e8f\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thei.edu.hk\\\/tc\\\/#website\",\"url\":\"https:\\\/\\\/thei.edu.hk\\\/tc\\\/\",\"name\":\"Technological and Higher Education Institute of Hong Kong\",\"description\":\"Technological and Higher Education Institute of Hong Kong\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thei.edu.hk\\\/tc\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-HK\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u7533\u8bf7\u7a0b\u5e8f - Technological and Higher Education Institute of Hong Kong","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thei.edu.hk\/tc\/admission\/\u7533\u8acb\u5165\u8b80\/\u7533\u8bf7\u7a0b\u5e8f\/","og_locale":"zh_HK","og_type":"article","og_title":"\u7533\u8bf7\u7a0b\u5e8f - Technological and Higher Education Institute of Hong Kong","og_description":"\u7533\u8bf7\u6d41\u7a0b\u53ca\u91cd\u8981\u65e5\u671f \u6309\u6b64\u7533\u8bf7 1 \u7f51\u4e0a\u5165\u5b66\u7533\u8bf7 \u901a\u8fc7\u7f51\u4e0a\u5165\u5b66\u7533\u8bf7\u7cfb\u7edf\u63d0\u4ea4\u7533\u8bf7\uff0c\u5e76\u4e0a\u4f20\u5b66\u5386\u8bc1\u660e\u53ca\u5176\u4ed6\u76f8\u5173\u6587\u4ef6\u526f\u672c\u3002 \u4e00\u5e74\u7ea7\u5165\u5b66\u7533\u8bf7\u987b\u901a\u8fc7\u7f51\u4e0a\u652f\u4ed8\u5e73\u53f0\u4ee5\u94f6\u8054\uff0c\u652f\u4ed8\u5b9d\u6216\u5fae\u4fe1\u652f\u4ed8\u7f34\u4ed8\u7533\u8bf7\u8d39\u6e2f\u5e01600\u5143\u3002 2 \u622a\u6b62\u7533\u8bf7\u65e5\u671f \u4ee5\u5e94\u5c4a\u9ad8\u8003\u6210\u7ee9\u7533\u8bf7\u5165\u8bfb\u4e00\u5e74\u7ea7\uff1a 2026\u5e746\u670825\u65e5\u4ee5\u5176\u4ed6\u5b66\u5386\u7533\u8bf7\u5165\u8bfb\u4e00\u5e74\u7ea7\uff1a2026\u5e747\u670831\u65e5\u3002 3 \u516c\u5e03\u5f55\u53d6\u901a\u77e5 \u4ee5\u5e94\u5c4a\u9ad8\u8003\u6210\u7ee9\u7533\u8bf7\u5165\u8bfb\u4e00\u5e74\u7ea7\uff1a2026\u5e746\u6708\u5e95\u81f37\u67087\u65e5*\u4ee5\u5176\u4ed6\u5b66\u5386\u7533\u8bf7\u5165\u8bfb\u4e00\u5e74\u7ea7\uff1a\u4e0d\u8fdf\u4e8e2026\u5e748\u6708(\u5f85\u5b9a)* \u4e0d\u540c\u7701\u5e02\u7684\u6295\u6863\u65e5\u671f\u53ca\u5b89\u6392\u5404\u6709\u4e0d\u540c\uff0c\u76f8\u5173\u5177\u4f53\u6d41\u7a0b\u5c06\u4f9d\u636e\u6559\u80b2\u90e8\u5ba3\u5e03\u4e4b\u9ad8\u8003\u53ca\u5f55\u53d6\u653f\u7b56\u4f5c\u51fa\u53ca\u65f6\u8c03\u6574\u3002\u5b66\u9662\u4ea6\u4f1a\u6839\u636e\u5b9e\u9645\u5f55\u53d6\u60c5\u51b5\u800c\u63d0\u524d\u7ed3\u675f\u5f55\u53d6\u5de5\u4f5c\u3002 4 \u5165\u5b66\u6ce8\u518c\u53ca\u8fce\u65b0\u6d3b\u52a8 \u83b7\u5f55\u53d6\u7684\u540c\u5b66\u8bf7\u65bc8\u6708\u4e0b\u65ec\u81f3 9 \u6708\u521d(\u6682\u5b9a)\u6765\u6e2f\u6ce8\u518c\u5165\u5b66\u53ca\u53c2\u52a0\u8fce\u65b0\u6d3b\u52a8\u3002\u5b66\u751f\u987b\u5728\u5f55\u53d6\u901a\u77e5\u4e66\u7684\u6307\u5b9a\u9650\u671f\u524d, \u6309\u7f34\u8d39\u901a\u77e5\u4e66\u7684\u6307\u793a\u7f34\u4ed8\u7b2c\u4e00\u671f\u5b66\u8d39\u53ca\u5b66\u751f\u670d\u52a1\u8d39\u7b49\u8d39\u7528\u3002 \u7533\u8bf7\u4eba\u5982\u57282026\u5e741\u670831\u65e5\u6216\u4e4b\u524d\u63d0\u4ea4\u7533\u8bf7\uff0c\u5373\u53ef\u4ee5\u65e9\u9e1f\u4f18\u60e0\u4ef7\u6e2f\u5e01300\u5143\u7533\u8bf7\u4e00\u5e74\u7ea7\u5165\u5b66\uff1b\u5728\u6b64\u65e5\u671f\u540e\u63d0\u4ea4\uff0c\u7533\u8bf7\u8d39\u4e3a\u6e2f\u5e01600\u5143\u3002 \u5185\u573031\u4e2a\u7701\u4efd\u3001\u81ea\u6cbb\u533a\u53ca\u76f4\u8f96\u5e02\u7684\u5e94\u5c4a\u9ad8\u8003\u751f\u5747\u53ef\u7533\u8bf7THEi\u9ad8\u79d1\u9662\u672c\u79d1\u5165\u5b66\u3002\u5831\u8bfbTHEi\u9ad8\u79d1\u9662\u4e0d\u5360\u300c\u5168\u56fd\u666e\u901a\u9ad8\u6821\u7edf\u4e00\u62db\u751f\u8ba1\u5212\u300d\uff08\u7edf\u62db\uff09\u5fd7\u613f\u3002\u6839\u636e\u56fd\u5bb6\u6559\u80b2\u90e8\u89c4\u5b9a\uff0c\u5185\u5730\u5b66\u751f\u82e5\u83b7\u5f97\u9ad8\u79d1\u9662\u5f55\u53d6\u5e76\u63a5\u7eb3\u6709\u5173\u5b66\u7c4d\uff0c\u5185\u5730\u7edf\u62db\u9ad8\u6821\u5c06\u4e0d\u518d\u4e88\u4ee5\u5f55\u53d6\u3002 \u6309\u6b64\u7533\u8bf7 1 \u7f51\u4e0a\u5165\u5b66\u7533\u8bf7 \u901a\u8fc7\u7f51\u4e0a\u5165\u5b66\u7533\u8bf7\u7cfb\u7edf\u63d0\u4ea4\u7533\u8bf7\uff0c\u5e76\u4e0a\u4f20\u5b66\u5386\u8bc1\u660e\uff0c\u8bfe\u7a0b\u5927\u7eb2\u53ca\u5176\u4ed6\u76f8\u5173\u6587\u4ef6\u526f\u672c\u3002 \u4e8c\u3001\u4e09\u5e74\u7ea7\u5165\u5b66\u7533\u8bf7\u65e0\u987b\u7e73\u4ea4\u7533\u8bf7\u8d39\u3002 2 \u622a\u6b62\u7533\u8bf7\u65e5\u671f \u7533\u8bf7\u4e8c\u53ca\u4e09\u5e74\u7ea7\u5165\u5b66\uff1a 2026\u5e747\u670831\u65e5 3 \u516c\u5e03\u5f55\u53d6\u901a\u77e5 \u4e0d\u8fdf\u4e8e2026\u5e748\u6708(\u5f85\u5b9a) 4 \u5165\u5b66\u6ce8\u518c\u53ca\u8fce\u65b0\u6d3b\u52a8 \u83b7\u5f55\u53d6\u7684\u540c\u5b66\u8bf7\u65bc8\u6708\u4e0b\u65ec\u81f3 9 \u6708\u521d(\u6682\u5b9a)\u6765\u6e2f\u6ce8\u518c\u5165\u5b66\u53ca\u53c2\u52a0\u8fce\u65b0\u6d3b\u52a8\u3002\u5b66\u751f\u987b\u5728\u5f55\u53d6\u901a\u77e5\u4e66\u7684\u6307\u5b9a\u9650\u671f\u524d, \u6309\u7f34\u8d39\u901a\u77e5\u4e66\u7684\u6307\u793a\u7f34\u4ed8\u7b2c\u4e00\u671f\u5b66\u8d39\u53ca\u5b66\u751f\u670d\u52a1\u8d39\u7b49\u8d39\u7528\u3002 &hellip;","og_url":"https:\/\/thei.edu.hk\/tc\/admission\/\u7533\u8acb\u5165\u8b80\/\u7533\u8bf7\u7a0b\u5e8f\/","og_site_name":"Technological and Higher Education Institute of Hong Kong","article_modified_time":"2026-07-28T08:41:17+00:00","og_image":[{"url":"https:\/\/thei.edu.hk\/wp-content\/uploads\/2025\/01\/Application-button-11.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"\u9810\u8a08\u95b1\u8b80\u6642\u9593":"1 \u5206\u9418"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/thei.edu.hk\/tc\/admission\/%e7%94%b3%e8%ab%8b%e5%85%a5%e8%ae%80\/%e7%94%b3%e8%af%b7%e7%a8%8b%e5%ba%8f\/","url":"https:\/\/thei.edu.hk\/tc\/admission\/%e7%94%b3%e8%ab%8b%e5%85%a5%e8%ae%80\/%e7%94%b3%e8%af%b7%e7%a8%8b%e5%ba%8f\/","name":"\u7533\u8bf7\u7a0b\u5e8f - Technological and Higher Education Institute of Hong Kong","isPartOf":{"@id":"https:\/\/thei.edu.hk\/tc\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thei.edu.hk\/tc\/admission\/%e7%94%b3%e8%ab%8b%e5%85%a5%e8%ae%80\/%e7%94%b3%e8%af%b7%e7%a8%8b%e5%ba%8f\/#primaryimage"},"image":{"@id":"https:\/\/thei.edu.hk\/tc\/admission\/%e7%94%b3%e8%ab%8b%e5%85%a5%e8%ae%80\/%e7%94%b3%e8%af%b7%e7%a8%8b%e5%ba%8f\/#primaryimage"},"thumbnailUrl":"https:\/\/thei.edu.hk\/wp-content\/uploads\/2025\/01\/Application-button-11.jpg","datePublished":"2024-10-03T16:00:07+00:00","dateModified":"2026-07-28T08:41:17+00:00","breadcrumb":{"@id":"https:\/\/thei.edu.hk\/tc\/admission\/%e7%94%b3%e8%ab%8b%e5%85%a5%e8%ae%80\/%e7%94%b3%e8%af%b7%e7%a8%8b%e5%ba%8f\/#breadcrumb"},"inLanguage":"zh-HK","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thei.edu.hk\/tc\/admission\/%e7%94%b3%e8%ab%8b%e5%85%a5%e8%ae%80\/%e7%94%b3%e8%af%b7%e7%a8%8b%e5%ba%8f\/"]}]},{"@type":"ImageObject","inLanguage":"zh-HK","@id":"https:\/\/thei.edu.hk\/tc\/admission\/%e7%94%b3%e8%ab%8b%e5%85%a5%e8%ae%80\/%e7%94%b3%e8%af%b7%e7%a8%8b%e5%ba%8f\/#primaryimage","url":"https:\/\/thei.edu.hk\/wp-content\/uploads\/2025\/01\/Application-button-11.jpg","contentUrl":"https:\/\/thei.edu.hk\/wp-content\/uploads\/2025\/01\/Application-button-11.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/thei.edu.hk\/tc\/admission\/%e7%94%b3%e8%ab%8b%e5%85%a5%e8%ae%80\/%e7%94%b3%e8%af%b7%e7%a8%8b%e5%ba%8f\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thei.edu.hk\/"},{"@type":"ListItem","position":2,"name":"Admission","item":"https:\/\/thei.edu.hk\/admission\/"},{"@type":"ListItem","position":3,"name":"\u7533\u8acb\u5165\u8b80","item":"https:\/\/thei.edu.hk\/admission\/%e7%94%b3%e8%ab%8b%e5%85%a5%e8%ae%80\/"},{"@type":"ListItem","position":4,"name":"\u7533\u8bf7\u7a0b\u5e8f"}]},{"@type":"WebSite","@id":"https:\/\/thei.edu.hk\/tc\/#website","url":"https:\/\/thei.edu.hk\/tc\/","name":"Technological and Higher Education Institute of Hong Kong","description":"Technological and Higher Education Institute of Hong Kong","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thei.edu.hk\/tc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-HK"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-10 01:59:08","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"author","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/thei.edu.hk\/tc\/wp-json\/wp\/v2\/pages\/24178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thei.edu.hk\/tc\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/thei.edu.hk\/tc\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/thei.edu.hk\/tc\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/thei.edu.hk\/tc\/wp-json\/wp\/v2\/comments?post=24178"}],"version-history":[{"count":54,"href":"https:\/\/thei.edu.hk\/tc\/wp-json\/wp\/v2\/pages\/24178\/revisions"}],"predecessor-version":[{"id":77085,"href":"https:\/\/thei.edu.hk\/tc\/wp-json\/wp\/v2\/pages\/24178\/revisions\/77085"}],"up":[{"embeddable":true,"href":"https:\/\/thei.edu.hk\/tc\/wp-json\/wp\/v2\/pages\/24170"}],"wp:attachment":[{"href":"https:\/\/thei.edu.hk\/tc\/wp-json\/wp\/v2\/media?parent=24178"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/thei.edu.hk\/tc\/wp-json\/wp\/v2\/ppma_author?post=24178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}